{"id":1419,"date":"2015-09-09T11:08:47","date_gmt":"2015-09-09T09:08:47","guid":{"rendered":"http:\/\/www.happyparents.com\/blog\/?p=1419"},"modified":"2015-09-09T11:38:29","modified_gmt":"2015-09-09T09:38:29","slug":"le-soutien-scolaire-en-ligne-de-bernadette-en-maths-francais-anglais-pour-le-primaire-et-college-fait-des-heureux-y-compris-chez-les-dys","status":"publish","type":"post","link":"https:\/\/www.happyparents.com\/blog\/formation-parents\/le-soutien-scolaire-en-ligne-de-bernadette-en-maths-francais-anglais-pour-le-primaire-et-college-fait-des-heureux-y-compris-chez-les-dys-1419.html","title":{"rendered":"Le soutien scolaire en ligne de Bernadette en Maths, Fran\u00e7ais, Anglais pour le primaire et coll\u00e8ge fait des heureux y compris chez les dys&#8230;"},"content":{"rendered":"<p><em>Bonjour,<\/em><\/p>\n<p><em>Oui j\u2019ai pu me connecter sans probl\u00e8me \u00e0 l\u2019universit\u00e9 des parents.<\/em><br \/>\n<em>J\u2019ai d\u00e9j\u00e0 pu consulter quelques vid\u00e9os avec mon fils.<\/em><br \/>\n<em>Je vous f\u00e9licite pour votre approche de l\u2019enseignement d\u00e9di\u00e9 aux enfants.<\/em><br \/>\n<em>Un grand bravo.<\/em><br \/>\n<em>Meilleures salutations<\/em><br \/>\nA. Constant<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;-<br \/>\n<em>Bonjour,<\/em><br \/>\n<em> Je suis ravie de pouvoir profiter de votre tr\u00e8s bon travail.<\/em><br \/>\n<em> Ma fille de 9 ans et demi a pris vos conseils pour expliquer les conversions \u00e0 ses copines.<\/em><br \/>\n<em> Merci d&#8217;avoir pris de mes nouvelles.<\/em><br \/>\n<em> A bient\u00f4t<\/em><br \/>\nChantal M.<br \/>\n<em>Bonjour Bernadette et Eric,<br \/>\n<\/em><em>Mon fils a eu la chance de voir vos vid\u00e9os sur les fractions pour r\u00e9viser pour son contr\u00f4le de Maths, il \u00e9tait ravi.<\/em><br \/>\nGr\u00e2ce D.<\/p>\n<p><em>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<br \/>\nBonjour,<\/em><br \/>\n<em>C&#8217;est pour ma fille qui est en CM2 qu&#8217;on utilise Universit\u00e9 Happyparents\u00a0Maths.<\/em><br \/>\n<em>En g\u00e9n\u00e9ral elle me dis qu&#8217;elle n&#8217;a pas compris en classe, donc on revoit ensemble la le\u00e7on\u00a0et apr\u00e8s on se tourne vers les vid\u00e9os pour avoir une autre explication.<\/em><br \/>\n<em>Elle utilise les vid\u00e9os enfants en autonomie puis elle faits ses exercices\u00a0puis je v\u00e9rifie si elle a bien compris.<\/em><br \/>\n<em>Pour l&#8217;instant ma fille et moi m\u00eame sommes satisfaite, merci.<\/em><br \/>\n<em>Cordialement<\/em><br \/>\nMme de V.<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/p>\n<p><em>Pour ce qui concerne les vid\u00e9os, mes \u00e9l\u00e8ves\u00a0sont contents. Je les encourage ensuite \u00e0 prendre l&#8217;abonnement chez eux,\u00a0vous avez d\u00fb d\u00e9j\u00e0 \u00eatre en contact avec mr B. pour sa fille, je ne sais pas si il a finalis\u00e9 ou pas.<\/em><br \/>\n<em>Quant qu&#8217;\u00e0 moi, les vid\u00e9os maths m&#8217;apprennent beaucoup, j&#8217;ai tout compris du th\u00e9or\u00e8me de\u00a0Pythagore\u00a0!!!! et oui, j&#8217;ai toujours \u00e9t\u00e9 nulle\u00a0en maths, du coup vos vid\u00e9os m&#8217;aident beaucoup pour \u00e0 mon tour\u00a0aider mes \u00e9l\u00e8ves quand ils me le demandent car ce n&#8217;est pas ma fonction premi\u00e8re que de travailler les contenus avec eux et surtout les maths (ce que je refusais de faire jusqu&#8217;\u00e0 pr\u00e9sent ne me sentant pas suffisamment efficiente)<\/em><br \/>\n<em> Voil\u00e0 ce que je peux vous dire pour l&#8217;instant.<br \/>\n<\/em>Martine M.<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<br \/>\n<em>Merci beaucoup ! Vos vid\u00e9os m&#8217;ont beaucoup aid\u00e9e et m&#8217;on fait comprendre en \u00e0 peine une heure ce que les autres s&#8217;arrachaient les cheveux a m&#8217;expliquer depuis longtemps. J&#8217;esp\u00e8re que mon contr\u00f4le se passera bien (maintenant il n&#8217;y a plus aucune raison) donc merci merci et milles fois merci ! \ud83d\ude00<\/em><br \/>\n<em>&#8230; Bonjour Madame, je tenais \u00e0 vous remercier et tout particuli\u00e8rement pour la vid\u00e9o que vous avez post\u00e9 aujourd&#8217;hui sur les in\u00e9quations. Merci !<\/em><br \/>\nMarie D. (enfant dyslexique d\u00e9sesp\u00e9r\u00e9e en arrivant)<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<br \/>\n<em>J&#8217;ai consult\u00e9 le module de d\u00e9couverte en y acc\u00e9dant facilement un soir o\u00f9 Cl\u00e9ment \u00e9tait d\u00e9j\u00e0 couch\u00e9.<\/em><br \/>\n<em>J&#8217;ai commenc\u00e9 \u00e0 regarder le d\u00e9but: les quatre r\u00e8gles de l&#8217;alg\u00e8bre et le r\u00e9flexe orthographique et j&#8217;ai trouv\u00e9 les explications tr\u00e8s\u00a0claires, concr\u00e8tes et faciles \u00e0 retenir. Bravo!<\/em><br \/>\n<em>Cet outil gratuit est effectivement recommandable \u00e0 d&#8217;autres familles.<\/em><br \/>\nPatrice L.<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/p>\n<p><em>Mes filles adorent\u00a0la fa\u00e7on\u00a0avec laquelle\u00a0Bernadette traite des diff\u00e9rents sujets et raffolent\u00a0des vid\u00e9os.<\/em><br \/>\n<em>J&#8217;avoue que pour l&#8217;instant elles en redemandent.<br \/>\n<\/em>Christelle J.<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/p>\n<p><em>Merci pour votre r\u00e9ponse ce week-end, la vid\u00e9o nous a permis de pr\u00e9parer le contr\u00f4le sur les nombres relatifs; c&#8217;est tr\u00e8s sympa, on a l&#8217;impression de vous avoir \u00e0 la maison.<\/em><br \/>\nNATHALIE G.<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/p>\n<p><em>Merci beaucoup,<\/em><br \/>\n<em>J&#8217;utilise \u00e9norm\u00e9ment vos vid\u00e9os avec mes petits-enfants et d&#8217;autres enfants qui sont en difficult\u00e9 d&#8217;apprentissage.<\/em><br \/>\n<em>Ils aiment bien et c&#8217;est une autre voix qui explique ce qui fait une r\u00e9vision diff\u00e9rente.<\/em><br \/>\n<em>Merci pour votre travail.<\/em><br \/>\n<em>Amiti\u00e9s<\/em><br \/>\nClaire-Lise T.<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<br \/>\n<em>Bonjour,<\/em><br \/>\n<em>Nous utilisons les fiches et les vid\u00e9os enfants.<\/em><br \/>\n<em>C\u2019est Valentin qui demande \u00e0 voir le cours sur la notion mal acquise.<\/em><br \/>\n<em>Les vid\u00e9os enfants sont tr\u00e8s claires et Valentin est tr\u00e8s r\u00e9ceptif. Les m\u00e9thodes donn\u00e9es sont tellement pleine de bon sens\u00a0!<\/em><br \/>\n<em>Parfois la m\u00e9thode n\u2019est pas celle donn\u00e9e en cours mais peu importe, l\u2019important \u00e9tant de comprendre la notion et Valentin comprend tr\u00e8s bien avec Bernadette (nous pouvons m\u00eame dire \u00ab\u00a0uniquement avec Bernadette\u00a0!!!)<\/em><br \/>\n<em>Les fiches sont concises, claires, faciles \u00e0 lire et \u00e0 comprendre. Nous les affichons au dessus du bureau sinon nous les conservons dans un classeur.<\/em><br \/>\n<em>Un 10\/10 sans aucune h\u00e9sitation, notre fils retrouve tout doucement le go\u00fbt d\u2019apprendre\u2026 le chemin va \u00eatre long mais il retrouve confiance et se sent mieux gr\u00e2ce \u00e0 vous\u2026.<\/em><br \/>\n<em>Quant au souhait que nous pouvons \u00e9mettre\u00a0:\u00a0 CONTINUEZ\u00a0!<\/em><br \/>\n<em>Encore un grand merci\u2026.<\/em><br \/>\nFamille G.<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/p>\n<p><em>Je suis maman de trois filles non scolaris\u00e9es de 10, 13, 14 ans (niveau 6eme, 4eme et seconde), depuis que nous avons d\u00e9couvert l\u2019\u00e9cole en ligne de Bernadette nous sommes ravies.mes filles utilisent les le\u00e7ons et vid\u00e9os de Fran\u00e7ais, Maths et Anglais tr\u00e8s fr\u00e9quemment.les vid\u00e9os sont tr\u00e8s enrichissantes et agr\u00e9ables, les cours papiers sont tr\u00e8s simples. Nous utilisons ces modules depuis plusieurs ann\u00e9es\u00a0 pour expliquer des le\u00e7ons mais aussi beaucoup pour r\u00e9viser.<\/em><br \/>\n<em>Apolline (10 ans) adore Bernadette. Avant, pendant et apr\u00e8s ses cours elle \u00e9coute les explications, les conseils avec un immense plaisir .l\u2019\u00e9cole a la maison + l\u2019\u00e9cole en ligne de Bernadette c\u2019est g\u00e9nial dit elle.<\/em><br \/>\n<em>Bernadette a une fa\u00e7on d\u2019expliquer que l\u2019on ne trouve pas ailleurs et mes enfants appr\u00e9cient beaucoup.<\/em><br \/>\n<em>Merci a Bernadette et Eric pour la qualit\u00e9 de leur travail, leur gentillesse, leur disponibilit\u00e9 et leur g\u00e9n\u00e9rosit\u00e9.<br \/>\n<\/em>Nathalie M.<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/p>\n<p><em>Manon me dit &#8221; j&#8217;ai aim\u00e9 la fa\u00e7on d&#8217;expliquer&#8221; et la fa\u00e7on que &#8220;Bernadette a de donner des astuces&#8221;&#8230;<\/em><br \/>\n<em> Mon fils (12 ans) a quant \u00e0 lui appr\u00e9ci\u00e9 votre facult\u00e9 \u00e0 aller \u00e0 l&#8217;essentiel sans fioritures (il a r\u00e9vis\u00e9 les statistiques).<\/em><br \/>\nPascale T.<\/p>\n<p>&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;<\/p>\n<p>Pour retrouver <a href=\"http:\/\/www.happyparents.com\/enfants\/universite-hapyparents-maths-et-francais\">l&#8217;\u00e9cole de Bernadette en ligne Maths Fran\u00e7ais Anglais cliquez-ici<\/a><\/p>\n<div class=\"tweetthis\" style=\"text-align:left;\"><p> <a target=\"_blank\" rel=\"nofollow\" class=\"tt\" href=\"http:\/\/twitter.com\/intent\/tweet?text=Le+soutien+scolaire+en+ligne+de+Bernadette+en+Maths%2C+Fran%C3%A7ais%2C+Anglais+pour+le+primaire+et+coll%C3%A8ge+fait+des+heureux+y+...+http%3A%2F%2Fhappyparents.com%2Fblog%2F%3Fp%3D1419\" title=\"Post&amp;eacute; sur TWITTER\"><img decoding=\"async\" class=\"nothumb\" src=\"https:\/\/www.happyparents.com\/blog\/wp-content\/plugins\/tweet-this\/icons\/en\/twitter\/tt-twitter.png\" alt=\"Post to Twitter\" \/><\/a> <a target=\"_blank\" rel=\"nofollow\" class=\"tt\" href=\"http:\/\/twitter.com\/intent\/tweet?text=Le+soutien+scolaire+en+ligne+de+Bernadette+en+Maths%2C+Fran%C3%A7ais%2C+Anglais+pour+le+primaire+et+coll%C3%A8ge+fait+des+heureux+y+...+http%3A%2F%2Fhappyparents.com%2Fblog%2F%3Fp%3D1419\" title=\"Post&amp;eacute; sur TWITTER\">Tweet ce message<\/a><\/p><\/div><div id=\"wp_fb_like_button\" style=\"margin:5px 0;float:none;height:100px;\"><script src=\"http:\/\/connect.facebook.net\/en_US\/all.js#xfbml=1\"><\/script><fb:like href=\"https:\/\/www.happyparents.com\/blog\/formation-parents\/le-soutien-scolaire-en-ligne-de-bernadette-en-maths-francais-anglais-pour-le-primaire-et-college-fait-des-heureux-y-compris-chez-les-dys-1419.html\" send=\"false\" layout=\"standard\" width=\"450\" show_faces=\"true\" font=\"arial\" action=\"like\" colorscheme=\"light\"><\/fb:like><\/div>","protected":false},"excerpt":{"rendered":"<p>Bonjour, Oui j\u2019ai pu me connecter sans probl\u00e8me \u00e0 l\u2019universit\u00e9 des parents. J\u2019ai d\u00e9j\u00e0 pu consulter quelques vid\u00e9os avec mon fils. Je vous f\u00e9licite pour votre approche de l\u2019enseignement d\u00e9di\u00e9 aux enfants. Un grand bravo. Meilleures salutations A. Constant &#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;&#8212;- Bonjour, Je suis ravie de pouvoir profiter de votre tr\u00e8s bon travail. Ma fille de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,4],"tags":[],"class_list":["post-1419","post","type-post","status-publish","format-standard","hentry","category-annonces-produits-services","category-formation-parents"],"_links":{"self":[{"href":"https:\/\/www.happyparents.com\/blog\/wp-json\/wp\/v2\/posts\/1419"}],"collection":[{"href":"https:\/\/www.happyparents.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.happyparents.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.happyparents.com\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.happyparents.com\/blog\/wp-json\/wp\/v2\/comments?post=1419"}],"version-history":[{"count":9,"href":"https:\/\/www.happyparents.com\/blog\/wp-json\/wp\/v2\/posts\/1419\/revisions"}],"predecessor-version":[{"id":1449,"href":"https:\/\/www.happyparents.com\/blog\/wp-json\/wp\/v2\/posts\/1419\/revisions\/1449"}],"wp:attachment":[{"href":"https:\/\/www.happyparents.com\/blog\/wp-json\/wp\/v2\/media?parent=1419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.happyparents.com\/blog\/wp-json\/wp\/v2\/categories?post=1419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.happyparents.com\/blog\/wp-json\/wp\/v2\/tags?post=1419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}